{"id":156843,"date":"2023-02-18T16:53:28","date_gmt":"2023-02-18T14:53:28","guid":{"rendered":"https:\/\/www.homecookingadventure.com\/?p=156843"},"modified":"2026-05-05T15:43:50","modified_gmt":"2026-05-05T12:43:50","slug":"biscuits-empreinte-au-citron-et-a-la-fraise","status":"publish","type":"post","link":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/","title":{"rendered":"Biscuits empreinte au citron et \u00e0 la fraise"},"content":{"rendered":"<!-- wp:paragraph -->\n<p>Ces biscuits empreinte au pouce fraise-citron sont une d\u00e9licieuse variante de la recette classique des biscuits empreinte au pouce. Un biscuit rapide et simple, au go\u00fbt d\u2019agrumes, fa\u00e7on craquel\u00e9, garni d\u2019une confiture de fraises maison sucr\u00e9e et d\u2019un gla\u00e7age au sucre citronn\u00e9. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Avec leurs couleurs vives et leurs saveurs rafra\u00eechissantes, ces biscuits sont parfaits pour les occasions du printemps et de l\u2019\u00e9t\u00e9. Les biscuits au citron se marient parfaitement avec la douceur de la confiture de fraises. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La combinaison des textures de ces biscuits est vraiment addictive, avec une base riche et une explosion de saveur \u00e0 chaque bouch\u00e9e. Ces biscuits sont faciles \u00e0 pr\u00e9parer et parfaits \u00e0 partager avec les amis et la famille.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Comment pr\u00e9parer des biscuits empreintes au pouce fraise-citron<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>D\u2019abord, pr\u00e9parez la p\u00e2te \u00e0 biscuits au citron. Pour cela, commencez par m\u00e9langer l\u2019\u0153uf avec le sucre, jusqu\u2019\u00e0 ce que le m\u00e9lange devienne p\u00e2le et cr\u00e9meux. Faites fondre les deux huiles et ajoutez-les au m\u00e9lange d\u2019\u0153uf. Ajoutez le zeste de citron, la vanille et le colorant alimentaire si vous en utilisez. Enfin, ajoutez tous les ingr\u00e9dients secs et continuez \u00e0 m\u00e9langer jusqu\u2019\u00e0 ce que la p\u00e2te forme une boule. Enveloppez-la dans du film alimentaire et r\u00e9frig\u00e9rez-la pendant au moins 2 heures ou toute une nuit.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Pour la confiture de fraises, vous pouvez utiliser des fraises fra\u00eeches ou surgel\u00e9es. Dans une casserole moyenne, portez \u00e0 \u00e9bullition les fraises et le sucre et laissez bouillir pendant 5 \u00e0 8 minutes. M\u00e9langez la f\u00e9cule de ma\u00efs avec l\u2019eau froide et ajoutez-la \u00e0 la confiture chaude. \u00c0 ce stade, vous pouvez ajouter la poudre de tonka si vous l\u2019utilisez. Continuez \u00e0 remuer \u00e0 feu doux pendant encore une minute. Laissez refroidir compl\u00e8tement. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":25839,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image size-full\"><img src=\"https:\/\/www.homecookingadventure.com\/wp-content\/uploads\/2023\/02\/Strawberry-lemon-thumbprint-cookies-main1.webp\" alt=\"Biscuits empreintes au citron avec confiture de fraises maison et gla\u00e7age au citron\" class=\"wp-image-25839\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Apr\u00e8s avoir refroidi la p\u00e2te, utilisez une cuill\u00e8re \u00e0 glace pour pr\u00e9lever des portions \u00e9gales de p\u00e2te et roulez-les en boules d\u2019environ 1 pouce (2,5 cm). Disposez-les en les espa\u00e7ant uniform\u00e9ment sur une plaque de cuisson recouverte de papier sulfuris\u00e9. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Utilisez votre pouce ou \u00bd c. \u00e0 caf\u00e9 pour faire une empreinte au centre de chaque biscuit. Faites cuire \u00e0 350F (180C) pendant environ 10 minutes. Tant qu\u2019ils sont encore chauds au toucher, \u00e0 l\u2019aide d\u2019une cuill\u00e8re, d\u00e9posez la confiture de fraises directement au milieu de chaque biscuit.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Pour le gla\u00e7age, m\u00e9langez simplement le sucre avec le jus de citron. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Garnissez les biscuits de confiture de fraises et arrosez-les du gla\u00e7age au sucre et au citron.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Vous allez adorer ces cookies et ils sont le choix id\u00e9al pour un pique-nique ou une f\u00eate d\u2019enfants ! J\u2019esp\u00e8re que vous essaierez ces rafra\u00eechissants cookies empreintes au citron et \u00e0 la fraise. Identifiez-moi sur <a href=\"https:\/\/www.instagram.com\/homecookingadventure\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a> si vous le faites et r\u00e9galez-vous !<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Autres biscuits \u00e0 empreinte de pouce que vous pourriez aimer essayer<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Si vous aimez les biscuits thumbprint, vous aimerez peut-\u00eatre aussi essayer ces <a href=\"https:\/\/www.homecookingadventure.com\/fr\/?p=157968\">biscuits thumbprint au chocolat<\/a> garnis de ganache au chocolat et d\u00e9cor\u00e9s de framboises lyophilis\u00e9es. Si vous aimez l\u2019association chocolat et beurre de cacahu\u00e8te, vous devez essayer ces <a href=\"https:\/\/www.homecookingadventure.com\/peanut-butter-chocolate-thumbprint-cookies\/\">biscuits thumbprint chocolat au beurre de cacahu\u00e8te<\/a>. L\u2019association des saveurs beurre de cacahu\u00e8te et chocolat est divine. Le beurre de cacahu\u00e8te n\u2019est pas envahissant, mais il apporte bien sa saveur unique \u00e0 ces d\u00e9licieux biscuits.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Autres desserts au citron et \u00e0 la fraise que vous pourriez aimer essayer<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Si vous aimez la combinaison fraise et citron, alors vous devez essayer ce rafra\u00eechissant<a href=\"https:\/\/www.homecookingadventure.com\/fr\/?p=157192\"> <strong>G\u00e2teau \u00e0 \u00e9tages fraise-citron<\/strong>.<\/a> Le g\u00e2teau se compose de quatre fines couches de g\u00e9noise vanille-citron, garnies d\u2019une g\u00e9n\u00e9reuse quantit\u00e9 de confiture de fraises fra\u00eechement pr\u00e9par\u00e9e et d\u2019un gla\u00e7age au citron et au mascarpone. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ces<a href=\"https:\/\/www.homecookingadventure.com\/fr\/?p=157194\"> <strong>roul\u00e9s \u00e0 la fraise sans \u0153ufs avec gla\u00e7age au citron et au fromage \u00e0 la cr\u00e8me<\/strong><\/a> sont tr\u00e8s faciles \u00e0 r\u00e9aliser et font toujours l\u2019unanimit\u00e9. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Essayez ces impressionnants <strong><a href=\"https:\/\/www.homecookingadventure.com\/fr\/?p=160442\">cupcakes fraise-citron<\/a> <\/strong>pour des mini-desserts individuels parfaits pour diverses occasions sp\u00e9ciales. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Si vous cherchez un dessert sans cuisson, essayez ce rafra\u00eechissant <a href=\"https:\/\/www.homecookingadventure.com\/fr\/?p=158174\"><strong>g\u00e2teau mousse yaourt citron aux fruits rouges sans cuisson<\/strong><\/a>. Le g\u00e2teau se compose d\u2019une cro\u00fbte croustillante de biscuits au citron, surmont\u00e9e d\u2019une mousse au yaourt citron, d\u2019une gel\u00e9e de fruits rouges, suivie d\u2019une mousse au yaourt aux fruits rouges et d\u00e9cor\u00e9e de fruits rouges frais.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":25837,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image size-full\"><img src=\"https:\/\/www.homecookingadventure.com\/wp-content\/uploads\/2023\/02\/Strawberry-lemon-thumbprint-cookies-vertical.webp\" alt=\"Biscuits empreintes au citron et \u00e0 la fraise avec confiture de fraises et gla\u00e7age au citron et au sucre\" class=\"wp-image-25837\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p><strong>VOUS AIMEREZ AUSSI :<\/strong><br><a href=\"https:\/\/www.homecookingadventure.com\/fr\/?p=158225\">Tarte au citron meringu\u00e9e<\/a><br><a href=\"https:\/\/www.homecookingadventure.com\/fr\/?p=157994\">G\u00e2teau au pavot avec lemon curd et chocolat blanc<\/a><br><a href=\"https:\/\/www.homecookingadventure.com\/lemon-bars\/\">Carr\u00e9s au citron<\/a><br><a href=\"https:\/\/www.homecookingadventure.com\/lemon-poppy-seed-pound-cake\/\">Quatre-quarts au citron et au pavot<\/a><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:wp-recipe-maker\/recipe {\"id\":156850,\"updated\":1777985004753} -->\n<!--WPRM Recipe 156850-->\n<div class=\"wprm-fallback-recipe\">\n\t<h2 class=\"wprm-fallback-recipe-name\">Biscuits empreintes au pouce fraise-citron<\/h2>\n\t<img class=\"wprm-fallback-recipe-image\" src=\"https:\/\/www.homecookingadventure.com\/wp-content\/uploads\/2023\/02\/Strawberry-lemon-thumbprint-cookies-main2-150x150.webp\"\/>\t<p class=\"wprm-fallback-recipe-summary\">\n\t\t<p>Ces biscuits empreintes au pouce fraise-citron sont une d\u00e9licieuse variante de la recette classique des biscuits empreintes au pouce. Un biscuit rapide et simple, au go\u00fbt d\u2019agrumes, de type craquel\u00e9, garni d\u2019une confiture de fraises maison sucr\u00e9e et d\u2019un gla\u00e7age au sucre citronn\u00e9. Avec leurs couleurs vives et leurs saveurs rafra\u00eechissantes, ces biscuits sont parfaits pour les occasions de printemps et d\u2019\u00e9t\u00e9. <\/p>\t<\/p>\n\t<div class=\"wprm-fallback-recipe-equipment\">\n\t\t\t<\/div>\n\t<div class=\"wprm-fallback-recipe-ingredients\">\n\t\t<h4>Biscuits au citron<\/h4><ul><li>1 \u0153uf<\/li><li>1\/2  tasse (100 g) sucre<\/li><li>20 ml huile v\u00e9g\u00e9tale<\/li><li>20 ml huile de coco (, fondue)<\/li><li>1 \u00bd tasse (190 g) farine tout usage<\/li><li>1 c. \u00e0 caf\u00e9 (4 g) levure chimique<\/li><li>1\/4  c. \u00e0 caf\u00e9 (1 g) sel<\/li><li>zeste de 2 citrons bio<\/li><li>1 c. \u00e0 caf\u00e9 (5 ml) extrait de vanille<\/li><li>colorant alimentaire jaune (, facultatif)<\/li><\/ul><h4>Confiture de fraises<\/h4><ul><li>150 g fraises (, fra\u00eeches ou surgel\u00e9es)<\/li><li>1\/4  tasse (50 g) sucre<\/li><li>1\/2  c. \u00e0 caf\u00e9 (2 g) poudre de tonka (, facultatif)<\/li><li>1  c. \u00e0 soupe (8 g) f\u00e9cule de ma\u00efs<\/li><li>1  c. \u00e0 caf\u00e9 (5 ml) eau froide<\/li><\/ul><h4>Gla\u00e7age au citron et au sucre<\/h4><ul><li>3 c. \u00e0 soupe (24 g) sucre glace<\/li><li>1 c. \u00e0 caf\u00e9 (5 ml) jus de citron<\/li><\/ul>\t<\/div>\n\t<div class=\"wprm-fallback-recipe-instructions\">\n\t\t<h4>Pr\u00e9parez la p\u00e2te \u00e0 biscuits au citron.<\/h4><ol><li><p>Dans un grand bol, \u00e0 l\u2019aide d\u2019un batteur \u00e9lectrique, fouettez l\u2019\u0153uf et le sucre jusqu\u2019\u00e0 ce que le m\u00e9lange blanchisse.<\/p><\/li><li><p>Ajoutez les huiles fondues, le zeste de citron, la vanille et le colorant alimentaire si utilis\u00e9, puis m\u00e9langez jusqu\u2019\u00e0 incorporation.<\/p><\/li><li><p>Ajoutez les ingr\u00e9dients secs et m\u00e9langez jusqu\u2019\u00e0 ce que la p\u00e2te se forme.<\/p><\/li><li><p>Formez une grosse boule de p\u00e2te, enveloppez-la dans du film alimentaire et r\u00e9frig\u00e9rez pendant au moins 2 heures.<\/p><\/li><\/ol><h4>Pr\u00e9parez la confiture de fraises.<\/h4><ol><li><p>Dans une casserole moyenne, portez \u00e0 \u00e9bullition les fraises et le sucre, puis laissez bouillir 5 \u00e0 8 minutes.<\/p><\/li><li><p>M\u00e9langez la f\u00e9cule de ma\u00efs avec l\u2019eau froide et ajoutez-la \u00e0 la confiture chaude. \u00c0 ce stade, vous pouvez ajouter la poudre de tonka si utilis\u00e9e.<\/p><\/li><li><p>Continuez \u00e0 remuer \u00e0 feu doux pendant encore une minute. Laissez refroidir compl\u00e8tement.<\/p><\/li><\/ol><h4>Faites cuire les biscuits et assemblez-les.<\/p><\/h4><ol><li><p>Pr\u00e9chauffez le four \u00e0 350\u00b0F (180\u00b0C). Tapissez deux plaques de cuisson de papier sulfuris\u00e9.<\/p><\/li><li><p>Une fois la p\u00e2te bien refroidie, utilisez une cuill\u00e8re \u00e0 glace pour pr\u00e9lever des portions \u00e9gales de p\u00e2te et roulez-les en boules d\u2019environ 1 pouce (2,5 cm). Disposez-les en les espa\u00e7ant sur une plaque recouverte de papier sulfuris\u00e9.<\/p><\/li><li><p>Avec votre pouce ou une cuill\u00e8re \u00e0 mesurer de \u00bd c. \u00e0 caf\u00e9, faites un creux au centre de chaque biscuit.<\/p><\/li><li><p>Faites cuire environ 8 \u00e0 10 minutes. Laissez refroidir avant de les garnir de confiture de fraises.<\/p><\/li><li><p>Tant qu\u2019ils sont encore ti\u00e8des, \u00e0 l\u2019aide d\u2019une cuill\u00e8re, d\u00e9posez la confiture de fraises au centre de chaque biscuit.<\/p><\/li><li><p>Une fois les biscuits refroidis, m\u00e9langez simplement le sucre avec le jus de citron et nappez les biscuits d\u2019un filet de gla\u00e7age au citron. R\u00e9galez-vous !<\/p><\/li><\/ol>\t<\/div>\n\t<div class=\"wprm-fallback-recipe-notes\">\n\t\t\t<\/div>\n\t<div class=\"wprm-fallback-recipe-meta\">\n\t\t<div class=\"wprm-fallback-recipe-meta-course\">Dessert<\/div><div class=\"wprm-fallback-recipe-meta-cuisine\">Am\u00e9ricaine<\/div><div class=\"wprm-fallback-recipe-meta-keyword\">Biscuits empreintes au pouce, citron, fraise<\/div>\t<\/div>\n<\/div>\n<!--End WPRM Recipe-->\n<!-- \/wp:wp-recipe-maker\/recipe -->\n\n<p><!-- \/wp:post-content --><\/p>","protected":false},"excerpt":{"rendered":"<p>Ces biscuits empreinte au pouce fraise-citron sont une d\u00e9licieuse variante de la recette classique des biscuits empreinte au pouce. Un biscuit rapide et simple, au go\u00fbt d\u2019agrumes, fa\u00e7on craquel\u00e9, garni d\u2019une confiture de fraises maison sucr\u00e9e et d\u2019un gla\u00e7age au sucre citronn\u00e9. Avec leurs couleurs vives et leurs saveurs rafra\u00eechissantes, ces biscuits sont parfaits pour &#8230;<\/p>\n","protected":false},"author":1,"featured_media":100752,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","loftocean_post_format_gallery":"","loftocean_post_format_gallery_ids":"","loftocean_post_format_gallery_urls":"","loftocean_post_format_video_id":0,"loftocean_post_format_video_url":"","loftocean_post_format_video_type":"","loftocean_post_format_video":"","loftocean_post_format_audio_type":"","loftocean_post_format_audio_url":"","loftocean_post_format_audio_id":0,"loftocean_post_format_audio":"","loftocean-featured-post":"","loftocean-like-count":0,"loftocean-view-count":268,"loftocean_coauthors":"","lemon_limes_single_post_intro_label":"","lemon_limes_single_post_intro_description":"","lemon_limes_single_post_hide_featured_image":"","lemon_limes_single_post_featured_media_position":"","lemon_limes_single_post_secondary_featured_image":25837,"lemon_limes_single_site_header_source":"","lemon_limes_single_custom_site_header":"0","lemon_limes_single_custom_sticky_site_header":"0","lemon_limes_single_custom_sticky_site_header_style":"scroll-up-enable","lemon_limes_single_site_footer_source":"","lemon_limes_single_custom_site_footer":"0","footnotes":""},"categories":[36883,36884,36833,36864,36894,36895,36885,36886,36893,13481,36836,36869,36889,13484],"tags":[37533,39278,39282,39269,39275,39271,37608,38139,39267],"class_list":["post-156843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-4-juillet","category-anniversaire","category-recettes-de-cookies","category-desserts-faciles","category-ete","category-hiver","category-noel","category-paques","category-printemps","category-recettes-a-petit-budget","category-recettes-americaines","category-recettes-de-mini-desserts","category-saint-valentin","category-sans-produits-laitiers","tag-thumbprint-cookies-4","tag-lemon-cookies-4","tag-lemon-thumbprint-cookies-4","tag-dairy-free-cookies-4","tag-how-to-make-thumbprint-cookies-4","tag-easy-cookie-recipe-4","tag-strawberry-recipes-4","tag-lemon-recipes-4","tag-cookie-recipes-4"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biscuits empreinte au citron et \u00e0 la fraise - Home Cooking Adventure<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez une variante p\u00e9tillante de biscuits empreinte : citron et fraise. Parfaits pour l&#039;\u00e9t\u00e9 avec confiture maison et gla\u00e7age citron!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biscuits empreinte au citron et \u00e0 la fraise - Home Cooking Adventure\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez une variante p\u00e9tillante de biscuits empreinte : citron et fraise. Parfaits pour l&#039;\u00e9t\u00e9 avec confiture maison et gla\u00e7age citron!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/\" \/>\n<meta property=\"og:site_name\" content=\"Home Cooking Adventure\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-18T14:53:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T12:43:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.homecookingadventure.com\/wp-content\/uploads\/2023\/02\/Strawberry-lemon-thumbprint-cookies-main2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Ella - Home Cooking Adventure\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ella - Home Cooking Adventure\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/biscuits-empreinte-au-citron-et-a-la-fraise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/biscuits-empreinte-au-citron-et-a-la-fraise\\\/\"},\"author\":{\"name\":\"Ella - Home Cooking Adventure\",\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/#\\\/schema\\\/person\\\/1cb86aa217ac391863fc17ffdc9eae4d\"},\"headline\":\"Biscuits empreinte au citron et \u00e0 la fraise\",\"datePublished\":\"2023-02-18T14:53:28+00:00\",\"dateModified\":\"2026-05-05T12:43:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/biscuits-empreinte-au-citron-et-a-la-fraise\\\/\"},\"wordCount\":1263,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/biscuits-empreinte-au-citron-et-a-la-fraise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.homecookingadventure.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Strawberry-lemon-thumbprint-cookies-main2.webp\",\"keywords\":[\"biscuits \u00e0 empreinte\",\"biscuits au citron\",\"biscuits empreinte au citron\",\"biscuits sans produits laitiers\",\"comment faire des biscuits empreintes de pouce\",\"recette de cookies facile\",\"Recettes \u00e0 la fraise\",\"Recettes au citron\",\"recettes de cookies\"],\"articleSection\":[\"4 juillet\",\"Anniversaire\",\"Cookies\",\"Desserts faciles\",\"\u00c9t\u00e9\",\"Hiver\",\"No\u00ebl\",\"P\u00e2ques\",\"Printemps\",\"Recettes \u00e0 petit budget\",\"Recettes am\u00e9ricaines\",\"Recettes de mini-desserts\",\"Saint Valentin\",\"Sans produits laitiers\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/biscuits-empreinte-au-citron-et-a-la-fraise\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/biscuits-empreinte-au-citron-et-a-la-fraise\\\/\",\"url\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/biscuits-empreinte-au-citron-et-a-la-fraise\\\/\",\"name\":\"Biscuits empreinte au citron et \u00e0 la fraise - Home Cooking Adventure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/biscuits-empreinte-au-citron-et-a-la-fraise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/biscuits-empreinte-au-citron-et-a-la-fraise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.homecookingadventure.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Strawberry-lemon-thumbprint-cookies-main2.webp\",\"datePublished\":\"2023-02-18T14:53:28+00:00\",\"dateModified\":\"2026-05-05T12:43:50+00:00\",\"description\":\"D\u00e9couvrez une variante p\u00e9tillante de biscuits empreinte : citron et fraise. Parfaits pour l'\u00e9t\u00e9 avec confiture maison et gla\u00e7age citron!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/biscuits-empreinte-au-citron-et-a-la-fraise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/biscuits-empreinte-au-citron-et-a-la-fraise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/biscuits-empreinte-au-citron-et-a-la-fraise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.homecookingadventure.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Strawberry-lemon-thumbprint-cookies-main2.webp\",\"contentUrl\":\"https:\\\/\\\/www.homecookingadventure.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Strawberry-lemon-thumbprint-cookies-main2.webp\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/biscuits-empreinte-au-citron-et-a-la-fraise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biscuits empreinte au citron et \u00e0 la fraise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/\",\"name\":\"Home Cooking Adventure\",\"description\":\"A Food Blog with Tested Recipes Using Everyday Ingredients\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/#organization\",\"name\":\"Home Cooking Adventure\",\"url\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.homecookingadventure.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/home-cooking-adventure-logo.webp\",\"contentUrl\":\"https:\\\/\\\/www.homecookingadventure.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/home-cooking-adventure-logo.webp\",\"width\":151,\"height\":80,\"caption\":\"Home Cooking Adventure\"},\"image\":{\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/#\\\/schema\\\/person\\\/1cb86aa217ac391863fc17ffdc9eae4d\",\"name\":\"Ella - Home Cooking Adventure\",\"url\":\"https:\\\/\\\/www.homecookingadventure.com\\\/fr\\\/author\\\/hca-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biscuits empreinte au citron et \u00e0 la fraise - Home Cooking Adventure","description":"D\u00e9couvrez une variante p\u00e9tillante de biscuits empreinte : citron et fraise. Parfaits pour l'\u00e9t\u00e9 avec confiture maison et gla\u00e7age citron!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/","og_locale":"fr_FR","og_type":"article","og_title":"Biscuits empreinte au citron et \u00e0 la fraise - Home Cooking Adventure","og_description":"D\u00e9couvrez une variante p\u00e9tillante de biscuits empreinte : citron et fraise. Parfaits pour l'\u00e9t\u00e9 avec confiture maison et gla\u00e7age citron!","og_url":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/","og_site_name":"Home Cooking Adventure","article_published_time":"2023-02-18T14:53:28+00:00","article_modified_time":"2026-05-05T12:43:50+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.homecookingadventure.com\/wp-content\/uploads\/2023\/02\/Strawberry-lemon-thumbprint-cookies-main2.webp","type":"image\/webp"}],"author":"Ella - Home Cooking Adventure","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ella - Home Cooking Adventure","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/#article","isPartOf":{"@id":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/"},"author":{"name":"Ella - Home Cooking Adventure","@id":"https:\/\/www.homecookingadventure.com\/fr\/#\/schema\/person\/1cb86aa217ac391863fc17ffdc9eae4d"},"headline":"Biscuits empreinte au citron et \u00e0 la fraise","datePublished":"2023-02-18T14:53:28+00:00","dateModified":"2026-05-05T12:43:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/"},"wordCount":1263,"commentCount":0,"publisher":{"@id":"https:\/\/www.homecookingadventure.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.homecookingadventure.com\/wp-content\/uploads\/2023\/02\/Strawberry-lemon-thumbprint-cookies-main2.webp","keywords":["biscuits \u00e0 empreinte","biscuits au citron","biscuits empreinte au citron","biscuits sans produits laitiers","comment faire des biscuits empreintes de pouce","recette de cookies facile","Recettes \u00e0 la fraise","Recettes au citron","recettes de cookies"],"articleSection":["4 juillet","Anniversaire","Cookies","Desserts faciles","\u00c9t\u00e9","Hiver","No\u00ebl","P\u00e2ques","Printemps","Recettes \u00e0 petit budget","Recettes am\u00e9ricaines","Recettes de mini-desserts","Saint Valentin","Sans produits laitiers"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/","url":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/","name":"Biscuits empreinte au citron et \u00e0 la fraise - Home Cooking Adventure","isPartOf":{"@id":"https:\/\/www.homecookingadventure.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/#primaryimage"},"image":{"@id":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.homecookingadventure.com\/wp-content\/uploads\/2023\/02\/Strawberry-lemon-thumbprint-cookies-main2.webp","datePublished":"2023-02-18T14:53:28+00:00","dateModified":"2026-05-05T12:43:50+00:00","description":"D\u00e9couvrez une variante p\u00e9tillante de biscuits empreinte : citron et fraise. Parfaits pour l'\u00e9t\u00e9 avec confiture maison et gla\u00e7age citron!","breadcrumb":{"@id":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/#primaryimage","url":"https:\/\/www.homecookingadventure.com\/wp-content\/uploads\/2023\/02\/Strawberry-lemon-thumbprint-cookies-main2.webp","contentUrl":"https:\/\/www.homecookingadventure.com\/wp-content\/uploads\/2023\/02\/Strawberry-lemon-thumbprint-cookies-main2.webp","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/www.homecookingadventure.com\/fr\/biscuits-empreinte-au-citron-et-a-la-fraise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.homecookingadventure.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Biscuits empreinte au citron et \u00e0 la fraise"}]},{"@type":"WebSite","@id":"https:\/\/www.homecookingadventure.com\/fr\/#website","url":"https:\/\/www.homecookingadventure.com\/fr\/","name":"Home Cooking Adventure","description":"A Food Blog with Tested Recipes Using Everyday Ingredients","publisher":{"@id":"https:\/\/www.homecookingadventure.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.homecookingadventure.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.homecookingadventure.com\/fr\/#organization","name":"Home Cooking Adventure","url":"https:\/\/www.homecookingadventure.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.homecookingadventure.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.homecookingadventure.com\/wp-content\/uploads\/2023\/01\/home-cooking-adventure-logo.webp","contentUrl":"https:\/\/www.homecookingadventure.com\/wp-content\/uploads\/2023\/01\/home-cooking-adventure-logo.webp","width":151,"height":80,"caption":"Home Cooking Adventure"},"image":{"@id":"https:\/\/www.homecookingadventure.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.homecookingadventure.com\/fr\/#\/schema\/person\/1cb86aa217ac391863fc17ffdc9eae4d","name":"Ella - Home Cooking Adventure","url":"https:\/\/www.homecookingadventure.com\/fr\/author\/hca-admin\/"}]}},"loftoceanMetas":{"authorName":"Ella - Home Cooking Adventure","categories":[{"name":"4 juillet","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/4-juillet\/","count":337},{"name":"Anniversaire","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/anniversaire\/","count":314},{"name":"Cookies","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/recettes-de-cookies\/","count":67},{"name":"Desserts faciles","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/desserts-faciles\/","count":423},{"name":"\u00c9t\u00e9","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/ete\/","count":639},{"name":"Hiver","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/hiver\/","count":681},{"name":"No\u00ebl","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/noel\/","count":472},{"name":"P\u00e2ques","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/paques\/","count":381},{"name":"Printemps","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/printemps\/","count":623},{"name":"Recettes \u00e0 petit budget","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/recettes-a-petit-budget\/","count":512},{"name":"Recettes am\u00e9ricaines","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/recettes-americaines\/","count":635},{"name":"Recettes de mini-desserts","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/recettes-de-mini-desserts\/","count":199},{"name":"Saint Valentin","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/saint-valentin\/","count":194},{"name":"Sans produits laitiers","link":"https:\/\/www.homecookingadventure.com\/fr\/Categorie\/sans-produits-laitiers\/","count":157}],"date":"f\u00e9vrier 18, 2023","featuredImageSRC":"https:\/\/www.homecookingadventure.com\/wp-content\/uploads\/2023\/02\/Strawberry-lemon-thumbprint-cookies-main2-150x150.webp"},"_links":{"self":[{"href":"https:\/\/www.homecookingadventure.com\/fr\/wp-json\/wp\/v2\/posts\/156843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.homecookingadventure.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.homecookingadventure.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.homecookingadventure.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.homecookingadventure.com\/fr\/wp-json\/wp\/v2\/comments?post=156843"}],"version-history":[{"count":3,"href":"https:\/\/www.homecookingadventure.com\/fr\/wp-json\/wp\/v2\/posts\/156843\/revisions"}],"predecessor-version":[{"id":162574,"href":"https:\/\/www.homecookingadventure.com\/fr\/wp-json\/wp\/v2\/posts\/156843\/revisions\/162574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.homecookingadventure.com\/fr\/wp-json\/wp\/v2\/media\/100752"}],"wp:attachment":[{"href":"https:\/\/www.homecookingadventure.com\/fr\/wp-json\/wp\/v2\/media?parent=156843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.homecookingadventure.com\/fr\/wp-json\/wp\/v2\/categories?post=156843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.homecookingadventure.com\/fr\/wp-json\/wp\/v2\/tags?post=156843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}